{"id":429,"date":"2008-02-10T21:13:34","date_gmt":"2008-02-10T19:13:34","guid":{"rendered":"http:\/\/www.aufabwegen.de\/magazin\/?p=429"},"modified":"2008-12-10T21:39:20","modified_gmt":"2008-12-10T19:39:20","slug":"muchezoubektang-sator-rotas-cd","status":"publish","type":"post","link":"https:\/\/www.aufabwegen.de\/magazin\/muchezoubektang-sator-rotas-cd\/","title":{"rendered":"Muche\/Zoubek\/Tang &#8211; Sator-Rotas CD"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-430\" title=\"cs109\" src=\"https:\/\/www.aufabwegen.de\/magazin\/wp-content\/uploads\/2008\/12\/cs109.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.aufabwegen.de\/magazin\/wp-content\/uploads\/2008\/12\/cs109.jpg 230w, https:\/\/www.aufabwegen.de\/magazin\/wp-content\/uploads\/2008\/12\/cs109-150x150.jpg 150w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/p>\n<p>Muche\/Zoubek\/Tang<br \/>\nSator-Rotas CD<br \/>\n(creative sources recordings cs109cd)<\/p>\n<p>Drei der Aktivposten aus K\u00f6lns lebendiger Improvszene haben sich eienr elektronischen Komposition angenommen und diese in ihr Metier frei transkribiert. In der akustischen Besetzung Kontrabass (Tang), pr\u00e4pariertes Klavier (Zoubek) und Posaune (Muche) wird Marcus Schmicklers St\u00fcck Sator-Rotas neu interpretiert. Die malmende Klangwalze besonders in der Verdichtung zum Ende des Tracks verdeutlicht die Vehemenz und das gar nicht zimperliche musikalische Denken Schmicklers. Die Instrumentalisten schaffen es aber vor allen Dingen, der Komposition eine neue Wendung, eine zus\u00e4tzlcihe Facette zu geben. Auch wenn es klischeehaft klingen mag: durch die kraftvoll mit K\u00f6rpereinsatz bedienten Instrumente spinenn sich lebendige F\u00e4den zwischen einzelnen Bl\u00f6cken des St\u00fccks, die dem Ganzen einen Human Touch geben, der in der sperrigen K\u00e4lte des Originals nicht zu finden ist. Herzlichen Dank hierf\u00fcr!<br \/>\n<em>Zipo<\/em><br \/>\nwww.creativesourcesrec.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muche\/Zoubek\/Tang Sator-Rotas CD (creative sources recordings cs109cd) Drei der Aktivposten aus K\u00f6lns lebendiger Improvszene haben sich eienr elektronischen Komposition angenommen und diese in ihr Metier frei transkribiert. In der akustischen Besetzung Kontrabass (Tang), pr\u00e4pariertes Klavier (Zoubek) und Posaune (Muche) wird Marcus Schmicklers St\u00fcck Sator-Rotas neu interpretiert. Die malmende Klangwalze besonders in der Verdichtung zum Ende [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[307,58,305,306],"tags":[],"class_list":["post-429","post","type-post","status-publish","format-standard","hentry","category-achim-tang","category-logbuch","category-matthias-muche","category-philip-zoubek","entry"],"_links":{"self":[{"href":"https:\/\/www.aufabwegen.de\/magazin\/wp-json\/wp\/v2\/posts\/429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aufabwegen.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aufabwegen.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aufabwegen.de\/magazin\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aufabwegen.de\/magazin\/wp-json\/wp\/v2\/comments?post=429"}],"version-history":[{"count":0,"href":"https:\/\/www.aufabwegen.de\/magazin\/wp-json\/wp\/v2\/posts\/429\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aufabwegen.de\/magazin\/wp-json\/wp\/v2\/media?parent=429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aufabwegen.de\/magazin\/wp-json\/wp\/v2\/categories?post=429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aufabwegen.de\/magazin\/wp-json\/wp\/v2\/tags?post=429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}